{"id":151991,"date":"2025-12-08T10:46:06","date_gmt":"2025-12-08T09:46:06","guid":{"rendered":"https:\/\/steitzsecura.com\/unkategorisiert\/new-shoe-series-duro-guard\/"},"modified":"2026-07-08T09:32:51","modified_gmt":"2026-07-08T07:32:51","slug":"new-shoe-series-duro-guard","status":"publish","type":"post","link":"https:\/\/steitzsecura.com\/en\/news-en\/new-shoe-series-duro-guard\/","title":{"rendered":"New shoe series DURO GUARD!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"151991\" class=\"elementor elementor-151991 elementor-108943\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cd1ffe e-flex e-con-boxed e-con e-parent\" data-id=\"8cd1ffe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-479a3f6 elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"479a3f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Post Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/steitzsecura.com\/en\/news-en\/new-developed-outsole-perbunan-multiflex\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Prev<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\"><\/span><span class=\"post-navigation__prev--title\">New developed outsole: Perbunan Multiflex<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/steitzsecura.com\/en\/news-en\/new-styles-with-extraguard-upper-material\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\"><\/span><span class=\"post-navigation__next--title\">New styles with EXTRAGUARD upper material<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Next<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04cf5e2 e-flex e-con-boxed e-con e-parent\" data-id=\"04cf5e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7037bc elementor-widget elementor-widget-heading\" data-id=\"b7037bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">  New shoe series DURO GUARD!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc0d3cf elementor-widget elementor-widget-image\" data-id=\"cc0d3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1463\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/12\/duroguard-beitrag-scaled.png\" class=\"attachment-full size-full wp-image-109035\" alt=\"\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/12\/duroguard-beitrag-scaled.png 2560w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/12\/duroguard-beitrag-300x171.png 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/12\/duroguard-beitrag-1024x585.png 1024w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/12\/duroguard-beitrag-768x439.png 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/12\/duroguard-beitrag-1536x878.png 1536w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/12\/duroguard-beitrag-2048x1170.png 2048w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/12\/duroguard-beitrag-1100x629.png 1100w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d00a6ce e-flex e-con-boxed e-con e-parent\" data-id=\"d00a6ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a42c552 elementor-widget elementor-widget-spacer\" data-id=\"a42c552\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3977909 elementor-widget elementor-widget-text-editor\" data-id=\"3977909\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>At the A+A 2025 in D\u00fcsseldorf STEITZ SECURA presented a completely new shoe series with eleven new styles. The DURO GUARD shoe series is designed for a variety of work environments and combines proven STEITZ SECURA features with innovative functions. Sturdy leather uppers are suitable for heavy-duty use, whilst lightweight microfibre versions are ideal for warehouses and production environments. For even greater comfort and safety, some models are fitted with the BOA\u00ae Fit System \u2013 allowing you to put them on and take them off quickly, adjust them with millimetre precision and enjoy a secure, long-lasting fit, all without the need for traditional laces. Furthermore, the DURO GUARD styles are equipped with a VF insole that offers textile puncture resistance. Moreover, the SECURA VARIO system with its weight-dependent exchangeable heel shock absorber modules supports individual comfort and perfect damping in every shoe.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98adac1 elementor-widget elementor-widget-button\" data-id=\"98adac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/steitzsecura.com\/en\/new-products-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">All features at a glance<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cca0b2 elementor-widget elementor-widget-text-editor\" data-id=\"8cca0b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>In addition, every style of this shoe is equipped with the new outsole <a href=\"https:\/\/steitzsecura.com\/en\/news-en\/new-developed-outsole-perbunan-multiflex\/\">Perbunan Multiflex<\/a>\u00a0that brings extra grip and flexibilty that support the wearer during work.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45891b3 elementor-grid-4 elementor-grid-tablet-3 elementor-grid-mobile-2 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"45891b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-4 \"><ul class=\"products elementor-grid columns-4\">\n<li class=\"product type-product post-98344 status-publish first instock product_cat-duro-guard-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<a href=\"https:\/\/steitzsecura.com\/en\/dg-9600-vf\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_vf-350x350.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"DG 9600 VF\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_vf-350x350.jpg 350w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_vf-300x300.jpg 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_vf-150x150.jpg 150w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_vf-768x768.jpg 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_vf-100x100.jpg 100w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_vf.jpg 1000w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><h2 class=\"woocommerce-loop-product__title\">DG 9600 VF<\/h2>\n<\/a><\/li>\n<li class=\"product type-product post-98262 status-publish instock product_cat-duro-guard-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<a href=\"https:\/\/steitzsecura.com\/en\/dg-9400-vf\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_vf-1-350x350.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"DG 9400 VF\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_vf-1-350x350.jpg 350w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_vf-1-300x300.jpg 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_vf-1-150x150.jpg 150w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_vf-1-768x768.jpg 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_vf-1-100x100.jpg 100w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_vf-1.jpg 1000w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><h2 class=\"woocommerce-loop-product__title\">DG 9400 VF<\/h2>\n<\/a><\/li>\n<li class=\"product type-product post-98257 status-publish instock product_cat-duro-guard-en product_cat-gore-tex-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<a href=\"https:\/\/steitzsecura.com\/en\/dg-9800-gtx-vf\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9800_gtx_vf-350x350.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"DG 9800 GTX VF\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9800_gtx_vf-350x350.jpg 350w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9800_gtx_vf-300x300.jpg 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9800_gtx_vf-150x150.jpg 150w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9800_gtx_vf-768x768.jpg 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9800_gtx_vf-100x100.jpg 100w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9800_gtx_vf.jpg 1000w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><h2 class=\"woocommerce-loop-product__title\">DG 9800 GTX VF<\/h2>\n<\/a><\/li>\n<li class=\"product type-product post-98358 status-publish last instock product_cat-duro-guard-en product_cat-gore-tex-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<a href=\"https:\/\/steitzsecura.com\/en\/dg-9400-gtx-boa-vf\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_gtx_boa_vf-350x350.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"DG 9400 GTX BOA VF\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_gtx_boa_vf-350x350.jpg 350w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_gtx_boa_vf-300x300.jpg 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_gtx_boa_vf-150x150.jpg 150w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_gtx_boa_vf-768x768.jpg 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_gtx_boa_vf-100x100.jpg 100w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_gtx_boa_vf.jpg 1000w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><h2 class=\"woocommerce-loop-product__title\">DG 9400 GTX BOA VF<\/h2>\n<\/a><\/li>\n<li class=\"product type-product post-100023 status-publish first instock product_cat-duro-guard-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<a href=\"https:\/\/steitzsecura.com\/en\/dg-9600-boa-vf\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_boa_vf-350x350.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"DG 9600 BOA VF\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_boa_vf-350x350.jpg 350w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_boa_vf-300x300.jpg 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_boa_vf-150x150.jpg 150w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_boa_vf-768x768.jpg 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_boa_vf-100x100.jpg 100w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9600_boa_vf.jpg 1000w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><h2 class=\"woocommerce-loop-product__title\">DG 9600 BOA VF<\/h2>\n<\/a><\/li>\n<li class=\"product type-product post-100020 status-publish instock product_cat-duro-guard-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<a href=\"https:\/\/steitzsecura.com\/en\/dg-9300-vf\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9300_vf-350x350.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"DG 9300 VF\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9300_vf-350x350.jpg 350w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9300_vf-300x300.jpg 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9300_vf-150x150.jpg 150w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9300_vf-768x768.jpg 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9300_vf-100x100.jpg 100w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9300_vf.jpg 1000w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><h2 class=\"woocommerce-loop-product__title\">DG 9300 VF<\/h2>\n<\/a><\/li>\n<li class=\"product type-product post-100021 status-publish instock product_cat-duro-guard-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<a href=\"https:\/\/steitzsecura.com\/en\/dg-9400-boa-vf\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_boa_vf-350x350.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"DG 9400 BOA VF\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_boa_vf-350x350.jpg 350w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_boa_vf-300x300.jpg 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_boa_vf-150x150.jpg 150w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_boa_vf-768x768.jpg 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_boa_vf-100x100.jpg 100w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9400_boa_vf.jpg 1000w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><h2 class=\"woocommerce-loop-product__title\">DG 9400 BOA VF<\/h2>\n<\/a><\/li>\n<li class=\"product type-product post-100022 status-publish last instock product_cat-duro-guard-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<a href=\"https:\/\/steitzsecura.com\/en\/dg-9500-vf\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9500_vf-350x350.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"DG 9500 VF\" srcset=\"https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9500_vf-350x350.jpg 350w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9500_vf-300x300.jpg 300w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9500_vf-150x150.jpg 150w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9500_vf-768x768.jpg 768w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9500_vf-100x100.jpg 100w, https:\/\/steitzsecura.com\/wp-content\/uploads\/2025\/10\/dg_9500_vf.jpg 1000w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><h2 class=\"woocommerce-loop-product__title\">DG 9500 VF<\/h2>\n<\/a><\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddf8fd2 elementor-widget elementor-widget-spacer\" data-id=\"ddf8fd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>New shoe series DURO GUARD! At the A+A 2025 in D\u00fcsseldorf STEITZ SECURA presented a completely new shoe series with eleven new styles. The DURO GUARD shoe series is designed for a variety of work environments and combines proven STEITZ SECURA features with innovative functions. Sturdy leather uppers are suitable for heavy-duty use, whilst lightweight [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":109035,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"At the A+A 2025 in D\u00fcsseldorf STEITZ SECURA presented a completely new shoe series with eleven new styles. The DURO GUARD shoe series is designed for a variety of work environments and combines proven STEITZ SECURA features with innovative functions.","_seopress_robots_index":"yes","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[951,974],"tags":[],"class_list":["post-151991","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news-en","category-product-novelties-and-innovations"],"acf":[],"_links":{"self":[{"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/posts\/151991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/comments?post=151991"}],"version-history":[{"count":8,"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/posts\/151991\/revisions"}],"predecessor-version":[{"id":152420,"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/posts\/151991\/revisions\/152420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/media\/109035"}],"wp:attachment":[{"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/media?parent=151991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/categories?post=151991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/steitzsecura.com\/en\/wp-json\/wp\/v2\/tags?post=151991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}